{"id":482,"date":"2023-03-10T12:18:22","date_gmt":"2023-03-10T12:18:22","guid":{"rendered":"https:\/\/clntranslations.teclan.org\/fort-augustus-und-die-abtei\/"},"modified":"2023-04-06T16:07:28","modified_gmt":"2023-04-06T15:07:28","slug":"fort-augustus-und-die-abtei","status":"publish","type":"post","link":"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/","title":{"rendered":"Fort Augustus und die Abtei"},"content":{"rendered":"\n<p>Nach Columban von Ionas Vorarbeit, die n\u00f6rdlichen Pikten zur Annahme des Christentums zu bewegen, schwankte die Region kontinuierlich zwischen heidnischen und christlichen Vorstellungen. Dies blieb so bis zur Ankunft von St. Cumin im Glen. Er kn\u00fcpfte an das Werk seines Vorg\u00e4ngers an und etablierte das Christentum in diesem Teil des Schottischen Hochlands restlos.  <\/p>\n\n<p>Er baute hier eine Kirche. Das Dorf wurde unter dem Namen \u201eCille Chuimein\u201c [Cumins Kirche] bekannt. Von den Einheimischen wird es auch weiterhin so genannt. Die Schule des Ortes hei\u00dft \u201eKilcumen Academy\u201c.  Nach dem zweiten Jakobitenaufstand im Jahre 1715 (die Jakobiten waren die Anh\u00e4nger der katholischen StuartMonarchie) lie\u00df General George Wade ein Stra\u00dfennetz mit Cille Chuimein als Mittelpunkt anlegen. <\/p>\n\n<p>Auch ein neues Fort baute er hier, das er zu Ehren des Lieblingssohns von Herzog Cumberland, der William Augustus hie\u00df, Fort Augustus nannte. Nach Fertigstellung des Forts wurde Fort Augustus der englische Name des Dorfes.  Das Fort hatte gewaltige Ausma\u00dfe und wies eine robuste Konstruktion auf. An jeder Ecke befanden sich vier schwer gesch\u00fctzte Basteien. Es bot einer starken Milit\u00e4reinheit Quartier.  <\/p>\n\n<p>Zum letzten Jakobitenaufstand kam es 1745. Das Fort kapitulierte vor jakobitischen Truppen, die es zuvor mit Kanonen schwer besch\u00e4digten. 1746 brachte der Herzog von Cumberland, nach dem das Fort benannt war, den Jakobiten eine Niederlage bei. Er entschloss, dort sein Hauptquartier einzurichten, doch es stellte sich als unbewohnbar heraus. Die vorgefundene Zerst\u00f6rung erz\u00fcrnte Cumberland und er beging an den Hochl\u00e4ndern eine Reihe von abscheulichen Schreckenstaten.  Nach 1745 wurde das Fort nicht mehr wiederhergestellt. Nachdem Lord Lovat es der Regierung abgekauft hatte, lie\u00df er ein Geb\u00e4ude zum Jagdhaus umfunktionieren. 1878 gab er das Fort an die Benediktinerm\u00f6nche, die an die Fundamente und die verbleibenden Geb\u00e4ude des Forts eine Abtei anbauten. <\/p>\n\n<p>Die M\u00f6nche betrieben hier bis 1993 eine Internatsschule und bis 1998 ein Besucherzentrum. Zu der Zeit war es die gr\u00f6\u00dfte im Privatbesitz befindliche Sehensw\u00fcrdigkeit in Schottland.  Die ansehnlichen Geb\u00e4ude wurden seitdem zu Apartments umgebaut und sind nicht mehr \u00f6ffentlich zug\u00e4nglich.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>An diesem Ende des Lochs besteht schon seit Beginn der Geschichtsschreibung eine Gemeinde.<\/p>\n","protected":false},"author":1,"featured_media":254,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_wp_rev_ctl_limit":""},"categories":[4],"tags":[],"class_list":["post-482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fort Augustus und die Abtei - Cruise Loch Ness<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fort Augustus und die Abtei - Cruise Loch Ness\" \/>\n<meta property=\"og:description\" content=\"An diesem Ende des Lochs besteht schon seit Beginn der Geschichtsschreibung eine Gemeinde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/\" \/>\n<meta property=\"og:site_name\" content=\"Cruise Loch Ness\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-10T12:18:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-06T15:07:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/guides.cruiselochness.com\/wp-content\/uploads\/2023\/03\/Cruise-Loch-Ness-53-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/fort-augustus-und-die-abtei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/fort-augustus-und-die-abtei\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/#\\\/schema\\\/person\\\/4d7b3d39612b01a39866e5e41da47f61\"},\"headline\":\"Fort Augustus und die Abtei\",\"datePublished\":\"2023-03-10T12:18:22+00:00\",\"dateModified\":\"2023-04-06T15:07:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/fort-augustus-und-die-abtei\\\/\"},\"wordCount\":341,\"publisher\":{\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/fort-augustus-und-die-abtei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/guides.cruiselochness.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Cruise-Loch-Ness-53-scaled.jpg\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/fort-augustus-und-die-abtei\\\/\",\"url\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/fort-augustus-und-die-abtei\\\/\",\"name\":\"Fort Augustus und die Abtei - Cruise Loch Ness\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/fort-augustus-und-die-abtei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/fort-augustus-und-die-abtei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/guides.cruiselochness.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Cruise-Loch-Ness-53-scaled.jpg\",\"datePublished\":\"2023-03-10T12:18:22+00:00\",\"dateModified\":\"2023-04-06T15:07:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/fort-augustus-und-die-abtei\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/fort-augustus-und-die-abtei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/fort-augustus-und-die-abtei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/guides.cruiselochness.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Cruise-Loch-Ness-53-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/guides.cruiselochness.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Cruise-Loch-Ness-53-scaled.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"Cruise Loch Ness\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/fort-augustus-und-die-abtei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fort Augustus und die Abtei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/\",\"name\":\"Cruise Loch Ness\",\"description\":\"Translations for your cruise\",\"publisher\":{\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/#organization\",\"name\":\"Cruise Loch Ness\",\"url\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/guides.cruiselochness.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/CLN-Logo-Transparent300w.png\",\"contentUrl\":\"https:\\\/\\\/guides.cruiselochness.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/CLN-Logo-Transparent300w.png\",\"width\":300,\"height\":137,\"caption\":\"Cruise Loch Ness\"},\"image\":{\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/#\\\/schema\\\/person\\\/4d7b3d39612b01a39866e5e41da47f61\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d86f2010536d862048714bba108d9175fd36952480c97c81ebc8940bfe0f0188?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d86f2010536d862048714bba108d9175fd36952480c97c81ebc8940bfe0f0188?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d86f2010536d862048714bba108d9175fd36952480c97c81ebc8940bfe0f0188?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/guides.cruiselochness.com\"],\"url\":\"https:\\\/\\\/guides.cruiselochness.com\\\/de\\\/author\\\/teclan_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fort Augustus und die Abtei - Cruise Loch Ness","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/","og_locale":"de_DE","og_type":"article","og_title":"Fort Augustus und die Abtei - Cruise Loch Ness","og_description":"An diesem Ende des Lochs besteht schon seit Beginn der Geschichtsschreibung eine Gemeinde.","og_url":"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/","og_site_name":"Cruise Loch Ness","article_published_time":"2023-03-10T12:18:22+00:00","article_modified_time":"2023-04-06T15:07:28+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/guides.cruiselochness.com\/wp-content\/uploads\/2023\/03\/Cruise-Loch-Ness-53-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/#article","isPartOf":{"@id":"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/"},"author":{"name":"admin","@id":"https:\/\/guides.cruiselochness.com\/de\/#\/schema\/person\/4d7b3d39612b01a39866e5e41da47f61"},"headline":"Fort Augustus und die Abtei","datePublished":"2023-03-10T12:18:22+00:00","dateModified":"2023-04-06T15:07:28+00:00","mainEntityOfPage":{"@id":"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/"},"wordCount":341,"publisher":{"@id":"https:\/\/guides.cruiselochness.com\/de\/#organization"},"image":{"@id":"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/#primaryimage"},"thumbnailUrl":"https:\/\/guides.cruiselochness.com\/wp-content\/uploads\/2023\/03\/Cruise-Loch-Ness-53-scaled.jpg","articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/","url":"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/","name":"Fort Augustus und die Abtei - Cruise Loch Ness","isPartOf":{"@id":"https:\/\/guides.cruiselochness.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/#primaryimage"},"image":{"@id":"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/#primaryimage"},"thumbnailUrl":"https:\/\/guides.cruiselochness.com\/wp-content\/uploads\/2023\/03\/Cruise-Loch-Ness-53-scaled.jpg","datePublished":"2023-03-10T12:18:22+00:00","dateModified":"2023-04-06T15:07:28+00:00","breadcrumb":{"@id":"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/#primaryimage","url":"https:\/\/guides.cruiselochness.com\/wp-content\/uploads\/2023\/03\/Cruise-Loch-Ness-53-scaled.jpg","contentUrl":"https:\/\/guides.cruiselochness.com\/wp-content\/uploads\/2023\/03\/Cruise-Loch-Ness-53-scaled.jpg","width":2560,"height":1706,"caption":"Cruise Loch Ness"},{"@type":"BreadcrumbList","@id":"https:\/\/guides.cruiselochness.com\/de\/fort-augustus-und-die-abtei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/guides.cruiselochness.com\/de\/"},{"@type":"ListItem","position":2,"name":"Fort Augustus und die Abtei"}]},{"@type":"WebSite","@id":"https:\/\/guides.cruiselochness.com\/de\/#website","url":"https:\/\/guides.cruiselochness.com\/de\/","name":"Cruise Loch Ness","description":"Translations for your cruise","publisher":{"@id":"https:\/\/guides.cruiselochness.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guides.cruiselochness.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/guides.cruiselochness.com\/de\/#organization","name":"Cruise Loch Ness","url":"https:\/\/guides.cruiselochness.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/guides.cruiselochness.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/guides.cruiselochness.com\/wp-content\/uploads\/2023\/03\/CLN-Logo-Transparent300w.png","contentUrl":"https:\/\/guides.cruiselochness.com\/wp-content\/uploads\/2023\/03\/CLN-Logo-Transparent300w.png","width":300,"height":137,"caption":"Cruise Loch Ness"},"image":{"@id":"https:\/\/guides.cruiselochness.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/guides.cruiselochness.com\/de\/#\/schema\/person\/4d7b3d39612b01a39866e5e41da47f61","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d86f2010536d862048714bba108d9175fd36952480c97c81ebc8940bfe0f0188?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d86f2010536d862048714bba108d9175fd36952480c97c81ebc8940bfe0f0188?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d86f2010536d862048714bba108d9175fd36952480c97c81ebc8940bfe0f0188?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/guides.cruiselochness.com"],"url":"https:\/\/guides.cruiselochness.com\/de\/author\/teclan_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/guides.cruiselochness.com\/de\/wp-json\/wp\/v2\/posts\/482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guides.cruiselochness.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guides.cruiselochness.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guides.cruiselochness.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guides.cruiselochness.com\/de\/wp-json\/wp\/v2\/comments?post=482"}],"version-history":[{"count":0,"href":"https:\/\/guides.cruiselochness.com\/de\/wp-json\/wp\/v2\/posts\/482\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guides.cruiselochness.com\/de\/wp-json\/wp\/v2\/media\/254"}],"wp:attachment":[{"href":"https:\/\/guides.cruiselochness.com\/de\/wp-json\/wp\/v2\/media?parent=482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guides.cruiselochness.com\/de\/wp-json\/wp\/v2\/categories?post=482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guides.cruiselochness.com\/de\/wp-json\/wp\/v2\/tags?post=482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}